{"id":332,"date":"2020-04-27T00:13:00","date_gmt":"2020-04-27T03:13:00","guid":{"rendered":"http:\/\/www.buildingprofits.com.br\/?p=332"},"modified":"2021-01-04T14:48:30","modified_gmt":"2021-01-04T14:48:30","slug":"desenquadramento-mei","status":"publish","type":"post","link":"http:\/\/priory.com.br\/bprh\/2020\/04\/27\/desenquadramento-mei\/","title":{"rendered":"Desenquadramento: o que fazer ao ultrapassar o limite de faturamento do MEI?"},"content":{"rendered":"\n<p>O Microempreendedor Individual\n(MEI) foi criado para regularizar a situa\u00e7\u00e3o de milhares de trabalhadores\naut\u00f4nomos que viviam na informalidade. Dessa forma, os microempreendedores\npassam a usufruir de benef\u00edcios como a emiss\u00e3o de notas, simplifica\u00e7\u00e3o de\nimpostos, financiamentos em bancos p\u00fablicos, al\u00e9m de previd\u00eancia social.<\/p>\n\n\n\n<p>Por outro lado, entre as\nexig\u00eancias do MEI est\u00e1 o rendimento anual limitado a R$ 81 mil, o que de certa\nforma pode dificultar a expans\u00e3o do neg\u00f3cio. Cabe ressaltar que o faturamento\nanual nada mais \u00e9 do que o somat\u00f3rio de todas as vendas realizadas ou de todos\nos servi\u00e7os prestados, sem a dedu\u00e7\u00e3o de nenhuma despesa. <\/p>\n\n\n\n<p>Quando limite \u00e9 ultrapassado, os\nmicroempreendedores s\u00e3o obrigados a comunicar o desenquadramento at\u00e9 o \u00faltimo\ndia \u00fatil do m\u00eas posterior \u00e0quele em que tenha ocorrido o excesso.<\/p>\n\n\n\n<p>H\u00e1 duas situa\u00e7\u00f5es de\ndesenquadramento. A Building Profits traz para voc\u00ea. Boa leitura!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Faturamento at\u00e9 20% acima do permitido<\/h2>\n\n\n\n<p>Se o faturamento ultrapassar o\nvalor, mas se limitar a R$ 97.200,00, ou seja, 20% acima do limite permitido, o\nMEI passa a se enquadrar na categoria de microempresa. Nessa situa\u00e7\u00e3o, ele\ncontinuar\u00e1 recolhendo o DAS na condi\u00e7\u00e3o de MEI at\u00e9 o m\u00eas de dezembro do ano em\nexerc\u00edcio.<\/p>\n\n\n\n<p>Nesses casos, al\u00e9m do DAS mensal\nde costume, o microempreendedor individual recolher\u00e1, tamb\u00e9m, um DAS\ncomplementar.<\/p>\n\n\n\n<p>Esse DAS complementar incide sobre\no excesso de faturamento e deve ser recolhido no m\u00eas de janeiro do ano\nseguinte. A partir de ent\u00e3o, o antigo MEI recolher\u00e1 na condi\u00e7\u00e3o de\nmicroempres\u00e1rio, tamb\u00e9m na categoria do Supersimples. <\/p>\n\n\n\n<p>Neste caso, os percentuais s\u00e3o a\npartir de 4% sobre o faturamento mensal, dependendo da atividade e do\nfaturamento. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Faturamento acima de 20% do\npermitido<\/strong><\/h2>\n\n\n\n<p>Em caso de faturamento superior a\nR$ 97.200,00, ou seja, acima dos 20% permitido, a condi\u00e7\u00e3o de desenquadramento\ndo MEI ser\u00e1 retroativa ao m\u00eas de janeiro e n\u00e3o apenas a partir do ano\nsubsequente. <\/p>\n\n\n\n<p>\u00c9 muito importante que o MEI\nrealize a gest\u00e3o financeira da sua empresa, para se antecipar em caso de\nexceder o faturamento permitido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Informa\u00e7\u00e3o relevante: o limite da\nReceita Bruta \u00e9 proporcional ao tempo de atividade<\/strong><\/h2>\n\n\n\n<p>Este \u00e9 um caso bastante ignorado\npelos microempreendedores individuais, por isso vale a pena ser lembrado. O\nexcesso da Receita Bruta ser\u00e1 calculado de forma proporcional ao tempo de\nabertura da empresa. Isso significa que \u00e9 preciso considerar o m\u00eas de inscri\u00e7\u00e3o\nno programa para saber se a empresa est\u00e1 dentro do limite exigido.<\/p>\n\n\n\n<p>Parece complicado, mas n\u00e3o \u00e9.\nConsiderando que o limite anual \u00e9 de R$ 81.000,00, proporcionalmente, o limite\nmensal seria de R$ 6.750,00. Dessa forma, o c\u00e1lculo deve ser feito\nmultiplicando o n\u00famero de meses de atividade da empresa no ano por R$ 6.750,00,\nque \u00e9 o limite mensal.<\/p>\n\n\n\n<p>Exemplo: <\/p>\n\n\n\n<p>\u27a1 In\u00edcio de atividade em setembro;<\/p>\n\n\n\n<p>\u27a1 At\u00e9 dezembro ser\u00e3o 4 meses de\natividade, portanto o limite ser\u00e1 de R$ 27.000,00;<\/p>\n\n\n\n<p>\u27a1 J\u00e1 os 20% do valor excedido ser\u00e1\nde R$ 32.400,00.<\/p>\n\n\n\n<p>Dessa forma, \u00e9 poss\u00edvel comparar\nos resultados para verificar se a empresa est\u00e1 dentro do limite proporcional ou\nse excedeu o faturamento.<\/p>\n\n\n\n<p>A Building Profits\nContabilidade \u00e9 especialista em solu\u00e7\u00f5es cont\u00e1beis customizadas para\nempresas de todos os portes. Torne a sua contabilidade mais din\u00e2mica,\ninteligente e rent\u00e1vel. Fale conosco: (41) 3028-8000 | comercial@buildingprofits.com.br.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Microempreendedor Individual (MEI) foi criado para regularizar a situa\u00e7\u00e3o de milhares de trabalhadores aut\u00f4nomos que viviam na informalidade. Dessa forma, os microempreendedores passam a usufruir de benef\u00edcios como a emiss\u00e3o de notas, simplifica\u00e7\u00e3o de impostos, financiamentos em bancos p\u00fablicos, al\u00e9m de previd\u00eancia social. Por outro lado, entre as exig\u00eancias do MEI est\u00e1 o rendimento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mei"],"_links":{"self":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts\/332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/comments?post=332"}],"version-history":[{"count":1,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts\/332\/revisions"}],"predecessor-version":[{"id":715,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts\/332\/revisions\/715"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/media\/613"}],"wp:attachment":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/media?parent=332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/categories?post=332"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/tags?post=332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}