{"id":683,"date":"2020-03-24T13:13:28","date_gmt":"2020-03-24T16:13:28","guid":{"rendered":"http:\/\/www.buildingprofits.com.br\/?p=325"},"modified":"2021-01-04T14:49:29","modified_gmt":"2021-01-04T14:49:29","slug":"mp-927-2020-trabalhista-coronavirus","status":"publish","type":"post","link":"http:\/\/priory.com.br\/bprh\/2020\/03\/24\/mp-927-2020-trabalhista-coronavirus\/","title":{"rendered":"MP 927\/2020: Rela\u00e7\u00f5es de trabalho em tempos de Coronav\u00edrus"},"content":{"rendered":"\n<p>A Building Profits traz aqui algumas orienta\u00e7\u00f5es jur\u00eddicas referentes \u00e0 Medida Provis\u00f3ria 927\/2020. Muitos questionamentos surgiram a partir da Medida Provis\u00f3ria publicada pelo Presidente da Rep\u00fablica. A medida estabelece uma s\u00e9rie de medidas trabalhistas que podem ser tomadas diante da pandemia do Coronav\u00edrus.<\/p>\n\n\n\n<p>O dispositivo legal relacionado \u00e0 suspens\u00e3o do contrato de trabalho j\u00e1 foi revogada pelo Governo, portanto, n\u00e3o tem mais validade, de modo que n\u00e3o poder\u00e1 ser feita a suspens\u00e3o do contrato de trabalho neste momento, sem lei ou acordo ou conven\u00e7\u00e3o coletiva nesse sentido.<\/p>\n\n\n\n<p>Destacamos que houve pronunciamento de que ser\u00e1 editada uma nova medida relacionada \u00e0 possibilidade da suspens\u00e3o, assegurando alguma remunera\u00e7\u00e3o aos empregados. Portanto, devemos aguardar as pr\u00f3ximas medidas do Governo Federal.<\/p>\n\n\n\n<p>A empresa teria como op\u00e7\u00e3o antecipar as f\u00e9rias individuais, instituir um banco de horas e realizar a antecipa\u00e7\u00e3o de feriados.<\/p>\n\n\n\n<p>A Building Profits detalha todas as novas regras atinentes a essas medidas (MP 927\/2020) abaixo. Boa leitura:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>DA ANTECIPA\u00c7\u00c3O DAS F\u00c9RIAS<\/strong><\/h2>\n\n\n\n<p>No per\u00edodo da calamidade p\u00fablica, o empregador poder\u00e1 comunicar o empregado sobre a antecipa\u00e7\u00e3o das suas f\u00e9rias com anteced\u00eancia de 48 horas, por escrito ou por meio eletr\u00f4nico, com a indica\u00e7\u00e3o do per\u00edodo a ser gozado pelo empregado.<\/p>\n\n\n\n<p>Por sua vez, as f\u00e9rias n\u00e3o poder\u00e3o ser gozadas em per\u00edodo inferiores a 5 dias, podendo ser concedidas por ato do empregador, ainda que o per\u00edodo aquisitivo ainda n\u00e3o tenha transcorrido. Nesse \u00faltimo caso, o empregado e empregador poder\u00e3o negociar a antecipa\u00e7\u00e3o de per\u00edodos futuros de f\u00e9rias, mediante acordo individual escrito.<\/p>\n\n\n\n<p>Quanto ao pagamento das f\u00e9rias, o empregador poder\u00e1 optar por efetuar o pagamento do adicional de 1\/3 de f\u00e9rias ap\u00f3s a sua concess\u00e3o, at\u00e9 a data em que \u00e9 devida a gratifica\u00e7\u00e3o natalina (13\u00ba sal\u00e1rio). J\u00e1 o pagamento da remunera\u00e7\u00e3o das f\u00e9rias poder\u00e1 ser efetuado at\u00e9 o 5\u00ba dia \u00fatil do m\u00eas subsequente ao gozo das f\u00e9rias, n\u00e3o aplicando o prazo previsto na CLT de dois dias antes do in\u00edcio das f\u00e9rias.<\/p>\n\n\n\n<p>Por fim, em caso de dispensa do empregado, o empregador pagar\u00e1, juntamente nos haveres rescis\u00f3rios, os valores que ainda n\u00e3o foram adimplidos relativos \u00e0s f\u00e9rias.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>DA CONCESS\u00c3O DAS F\u00c9RIAS COLETIVAS<\/strong><\/h2>\n\n\n\n<p>O empregador poder\u00e1 conceder f\u00e9rias coletivas, devendo notificar os empregados com anteced\u00eancia m\u00ednima de 48 horas, n\u00e3o aplic\u00e1veis o limite m\u00e1ximo de 2 per\u00edodos anuais e o limite m\u00ednimo de 10 dias corridos previstos na CLT. A Medida Provis\u00f3ria tamb\u00e9m dispensou a comunica\u00e7\u00e3o pr\u00e9via ao Minist\u00e9rio da Economia e a comunica\u00e7\u00e3o aos Sindicatos das categorias profissionais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">APROVEITAMENTO E ANTECIPA\u00c7\u00c3O DE FERIADOS<\/h2>\n\n\n\n<p>Durante o estado de calamidade p\u00fablica, os empregadores poder\u00e3o antecipar o gozo de feriados n\u00e3o religiosos federais, estaduais, distritais e municipais. Para tanto, dever\u00e1 notificar por escrito ou meio eletr\u00f4nico, o conjunto de empregados beneficiados com anteced\u00eancia m\u00ednima de 48 horas, devendo indicar expressamente quais ser\u00e3o os feriados aproveitados.<\/p>\n\n\n\n<p>Ademais, os feriados poder\u00e3o ser utilizados para a compensa\u00e7\u00e3o de saldo de banco de horas, caso existir.<\/p>\n\n\n\n<p>Por fim, com rela\u00e7\u00e3o aos feriados religiosos, a antecipa\u00e7\u00e3o depender\u00e1 de concord\u00e2ncia do empregado mediante manifesta\u00e7\u00e3o em acordo individual escrito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">BANCO DE HORAS<\/h2>\n\n\n\n<p>A Medida Provis\u00f3ria autorizou a interrup\u00e7\u00e3o das atividades pelo empregador e a constitui\u00e7\u00e3o de regime de compensa\u00e7\u00e3o de jornada, por meio do banco de horas, podendo ser estabelecido atrav\u00e9s de acordo coletivo ou acordo individual escrito.<\/p>\n\n\n\n<p>Nesse caso, a compensa\u00e7\u00e3o do per\u00edodo interrompido poder\u00e1 se dar por at\u00e9 18 (dezoito) meses, contado da data de encerramento do estado de calamidade p\u00fablica.<\/p>\n\n\n\n<p>A compensa\u00e7\u00e3o de tempo para recupera\u00e7\u00e3o do per\u00edodo interrompido poder\u00e1 ser feita mediante prorroga\u00e7\u00e3o de jornada em at\u00e9 duas horas, que n\u00e3o poder\u00e1 exceder dez horas di\u00e1rias.<\/p>\n\n\n\n<p>Continue acompanhando o blog da Building Profits para manter-se informado. Precisa de uma equipe remota que organiza sua vida cont\u00e1bil? Conte com a gente: <a href=\"mailto:comercial@buildingprofits.com.br\">comercial@buildingprofits.com.br<\/a>.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Building Profits traz aqui algumas orienta\u00e7\u00f5es jur\u00eddicas referentes \u00e0 Medida Provis\u00f3ria 927\/2020. Muitos questionamentos surgiram a partir da Medida Provis\u00f3ria publicada pelo Presidente da Rep\u00fablica. A medida estabelece uma s\u00e9rie de medidas trabalhistas que podem ser tomadas diante da pandemia do Coronav\u00edrus. O dispositivo legal relacionado \u00e0 suspens\u00e3o do contrato de trabalho j\u00e1 foi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado-de-trabalho"],"_links":{"self":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts\/683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":1,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts\/683\/revisions"}],"predecessor-version":[{"id":717,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts\/683\/revisions\/717"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/media\/611"}],"wp:attachment":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/categories?post=683"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}