{"id":694,"date":"2020-09-08T07:33:00","date_gmt":"2020-09-08T10:33:00","guid":{"rendered":"http:\/\/www.buildingprofits.com.br\/?p=376"},"modified":"2021-01-04T14:42:17","modified_gmt":"2021-01-04T14:42:17","slug":"analise-tributaria-e-contabil-de-perda-de-mercadoria","status":"publish","type":"post","link":"http:\/\/priory.com.br\/bprh\/2020\/09\/08\/analise-tributaria-e-contabil-de-perda-de-mercadoria\/","title":{"rendered":"Guia completo de an\u00e1lise tribut\u00e1ria e cont\u00e1bil de perda de mercadoria"},"content":{"rendered":"\n<p>Neste guia, a Building Profits re\u00fane todas as orienta\u00e7\u00f5es para o tratamento tribut\u00e1rio e cont\u00e1bil adequado \u00e0 perda de mercadorias do estoque. Voc\u00ea sabe, exatamente, como proceder no seu neg\u00f3cio diante das dificuldades de controle interno e gest\u00e3o de mercadorias? Leia at\u00e9 o fim!<\/p>\n\n\n\n<p>A perda de mercadorias n\u00e3o poderia ser algo comum, no entanto \u00e9 mais recorrente do que imaginamos. H\u00e1, portanto, sempre um vi\u00e9s nestas perdas a ser analisado de maneira mais minuciosa, pois elas podem impactar nos resultados (lucros ou perdas) da empresa e tamb\u00e9m diretamente na sua tributa\u00e7\u00e3o, a depender de seu regime tribut\u00e1rio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Principais tipos de perdas de mercadorias<\/strong><\/h2>\n\n\n\n<p><strong>Furtos<\/strong><\/p>\n\n\n\n<p>Infelizmente este \u00e9 um dos principais motivos de perda de mercadorias, pois acontecem por terceiros e at\u00e9 mesmo internamente, por pessoas da equipe de trabalho. Isso geralmente ocorre quando a seguran\u00e7a do local de armazenamento dos produtos n\u00e3o \u00e9 muito r\u00edgida, ou seja, o controle de entrada e sa\u00edda \u00e9 debilitado.<\/p>\n\n\n\n<p>Isso pode ser prevenido ou reduzido com um controle de estoque mais minucioso, realizando os registros adequados de entradas e sa\u00eddas, e tamb\u00e9m realizando contagens mais frequentes, a fim de mobilizar a equipe a ter maior aten\u00e7\u00e3o ao fluxo de mercadorias.<\/p>\n\n\n\n<p><strong>Avarias<\/strong><\/p>\n\n\n\n<p>Esta pode acontecer pelo mau cuidado no armazenamento ou transporte destes produtos, ocorrendo o dano total ou parcial da mercadoria.<\/p>\n\n\n\n<p>Infelizmente este cuidado tamb\u00e9m n\u00e3o depende apenas da empresa respons\u00e1vel pela mercadoria, pois pode chegar j\u00e1 danificado, seja pela empresa respons\u00e1vel pelo transporte ou armazenamento.<\/p>\n\n\n\n<p>A falta de equipamento de manuseio ou local adequado para seu armazenamento pode ocasionar esta perda. Ela pode ser evitada por meio de pol\u00edticas de boas pr\u00e1ticas e manuseio, investimento em instala\u00e7\u00f5es adequadas para armazenamento e confer\u00eancia no recebimento. Nessa \u00faltima situa\u00e7\u00e3o, caso j\u00e1 esteja com avaria, poder\u00e1 ser devolvido ao vendedor.<\/p>\n\n\n\n<p><strong>Falhas gerenciais e operacionais<\/strong><\/p>\n\n\n\n<p>At\u00e9 aqui j\u00e1 podemos observar que um bom controle de estoque \u00e9 essencial para evitar, ou minimizar, o risco de perda de mercadorias. A falha ou falta da gest\u00e3o de produtos podem tamb\u00e9m acarretar informa\u00e7\u00f5es incorretas e causar s\u00e9rios preju\u00edzos.<\/p>\n\n\n\n<p>Neste caso, a melhor op\u00e7\u00e3o \u00e9 investir em tecnologia. Sistemas integrados para controle de entrada e sa\u00eddas do estoque, fazendo com que a gest\u00e3o fique mais segura, consequentemente ir\u00e3o auxiliar na tomada de decis\u00e3o.<\/p>\n\n\n\n<p>Agora, vamos \u00e0s an\u00e1lises e pontos de aten\u00e7\u00e3o que sua equipe cont\u00e1bil precisa ter diante de alguns dos casos acima citados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Aspectos tribut\u00e1rios na perda de mercadorias<\/strong><\/h2>\n\n\n\n<p>Abaixo, voc\u00ea acompanha, caso a caso, como dever\u00e1 ser realizado o tratamento tribut\u00e1rio no caso de empresas inseridas em regimes de Lucro Presumido e Lucro Real, regime Cumulativo e N\u00e3o Cumulativo de PIS e Cofins.<\/p>\n\n\n\n<p><strong>Lucro Presumido<\/strong><\/p>\n\n\n\n<p>Em regra geral, no Lucro Presumido, somente o fato de ter ocasionado a perda de mercadorias por qualquer uma das formas citadas n\u00e3o influenciar\u00e1 na apura\u00e7\u00e3o, tendo em vista que sua tributa\u00e7\u00e3o \u00e9 gerada com base na receita auferida pela empresa.<\/p>\n\n\n\n<p>No entanto, cabe observar se esta perda de mercadorias estava acobertada por seguro e se houve o recebimento de indeniza\u00e7\u00e3o. Neste caso, haver\u00e1 o fato gerador de receita.<\/p>\n\n\n\n<p>Sendo assim, para fins tribut\u00e1rios na apura\u00e7\u00e3o do Lucro Presumido, os valores recebidos das seguradoras ser\u00e3o considerados como Receita Operacional da atividade, conforme conceito de Receita bruta determinado pelo artigo 12 do <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/Decreto-Lei\/Del1598.htm\">Decreto-Lei n\u00b0 1.598\/77<\/a>.<\/p>\n\n\n\n<p><strong>Lucro Real<\/strong><\/p>\n\n\n\n<p>Assim como nos demais regimes tribut\u00e1rios, dever\u00e1 manter-se periodicamente a apura\u00e7\u00e3o do invent\u00e1rio das mercadorias destinadas \u00e0 venda ou produ\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Essa apura\u00e7\u00e3o garante que o balan\u00e7o de encerramento de exerc\u00edcio social contemple a real situa\u00e7\u00e3o patrimonial da empresa. Em caso de poss\u00edveis ajustes, em decorr\u00eancia de diverg\u00eancias, dever\u00e3o ter notas explicativas destes ajustes.<\/p>\n\n\n\n<p>Para fins de dedutibilidade na apura\u00e7\u00e3o do Lucro Real, consideram-se integrantes do custo as perdas e quebras razo\u00e1veis. O valor ser\u00e1 de acordo com a natureza do bem, da atividade e da perda, se ocorrida na fabrica\u00e7\u00e3o, no transporte e no manuseio.<\/p>\n\n\n\n<p>H\u00e1 tamb\u00e9m as quebras e perdas de estoque por deteriora\u00e7\u00e3o, obsolesc\u00eancia ou pela ocorr\u00eancia de riscos n\u00e3o cobertos por seguros. Nesses casos, as perdas precisam ser comprovadas por laudos ou certificados emitidos por autoridade competente (autoridade sanit\u00e1ria ou de seguran\u00e7a, corpo de bombeiros, autoridade fiscal etc.) que especifiquem e identifiquem as quantidades destru\u00eddas ou inutilizadas e as raz\u00f5es da provid\u00eancia.<\/p>\n\n\n\n<p>Apenas as avarias \u00e9 que poder\u00e3o ser consideradas integrantes ao custo, e assim serem consideradas despesas dedut\u00edveis de acordo com o artigo 303 do RIR\/2018.<\/p>\n\n\n\n<p>Em regra geral, as demais perdas decorrentes de furtos, falhas gerenciais ou operacionais dever\u00e3o ser adicionadas na apura\u00e7\u00e3o do Lucro Real, conforme disp\u00f5e o artigo 260, inciso I do RIR\/2018.<\/p>\n\n\n\n<p>No entanto, nas perdas como roubo ou extors\u00e3o, a dedutibilidade poder\u00e1 ocorrer de forma an\u00e1loga, pois s\u00e3o figuras penais distintas do furto mas t\u00eam a mesma consequ\u00eancia deste.<\/p>\n\n\n\n<p>Quando n\u00e3o acobertada por seguro, a dedutibilidade somente estar\u00e1 assegurada quando houver inqu\u00e9rito instaurado nos termos da legisla\u00e7\u00e3o trabalhista, no caso de o autor ser colaborador da empresa ou quando apresenta not\u00edcia do crime perante autoridade policial.<\/p>\n\n\n\n<p>Observadas as condi\u00e7\u00f5es para dedutibilidade, poder\u00e1 realizar a dedu\u00e7\u00e3o de acordo com a forma de tributa\u00e7\u00e3o adotada.<\/p>\n\n\n\n<p><strong>Estimativa Real<\/strong><\/p>\n\n\n\n<p>A escritura\u00e7\u00e3o do livro de invent\u00e1rio dever\u00e1 obedecer \u00e0 mesma periodicidade do levantamento f\u00edsico dos estoques, sendo que a data-limite para sua legaliza\u00e7\u00e3o \u00e9 aquela prevista para o pagamento do imposto do mesmo per\u00edodo, ou seja no encerramento do ano-calend\u00e1rio, tendo em vista que durante os meses realiza o pagamento com base estimada. Sendo assim, somente no ajuste anual \u00e9 que ser\u00e3o realizadas as dedu\u00e7\u00f5es de perdas de mercadorias para fins de dedutibilidade.<\/p>\n\n\n\n<p>Caso o contribuinte adote o levantamento dos balancetes de suspens\u00e3o ou redu\u00e7\u00e3o do pagamento mensal, fica facultada \u00e0 pessoa jur\u00eddica realizar a avalia\u00e7\u00e3o mensal de seus estoques. Ao final de cada per\u00edodo anual, em 31 de dezembro, essa entrega \u00e9 obrigat\u00f3ria (RIR\/2018, artigo 304).<\/p>\n\n\n\n<p><strong>Trimestral<\/strong><\/p>\n\n\n\n<p>Conforme previsto no artigo 304 do RIR\/2018 ao final de cada per\u00edodo de apura\u00e7\u00e3o do imposto sobre a renda, a pessoa jur\u00eddica dever\u00e1 promover o levantamento e a avalia\u00e7\u00e3o dos seus estoques. Neste caso, tendo em vista as disposi\u00e7\u00f5es contidas na Lei n\u00b0 9.430\/96, que preveem a apura\u00e7\u00e3o do lucro real, base de c\u00e1lculo do imposto de renda, por per\u00edodos trimestrais, conclui-se que a pessoa jur\u00eddica estar\u00e1 obrigada a promover o levantamento e a avalia\u00e7\u00e3o dos seus estoques com a periodicidade de sua apura\u00e7\u00e3o trimestral. Ou seja, seguindo o calend\u00e1rio a seguir:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>31 de mar\u00e7o;<\/li><li>30 de junho;<\/li><li>30 de setembro;<\/li><li>e 31 de dezembro.<\/li><\/ul>\n\n\n\n<p><strong>Regime Cumulativo<\/strong><\/p>\n\n\n\n<p>Para este regime, as perdas n\u00e3o ir\u00e3o influenciar na apura\u00e7\u00e3o, tendo em vista que a base de c\u00e1lculo da Contribui\u00e7\u00e3o para o PIS\/Pasep e da Cofins \u00e9 o faturamento, conforme artigo 26, inciso II da Instru\u00e7\u00e3o Normativa RFB n\u00b0 1.911\/2019, n\u00e3o havendo a possibilidade de dedu\u00e7\u00e3o das perdas da base de c\u00e1lculo.<\/p>\n\n\n\n<p><strong>Regime N\u00e3o Cumulativo<\/strong><\/p>\n\n\n\n<p>Assim como no Regime Cumulativo, n\u00e3o h\u00e1 possibilidade de dedu\u00e7\u00e3o das perdas da base de c\u00e1lculo e sua tributa\u00e7\u00e3o ser\u00e1 a totalidade das receitas, independentemente de sua denomina\u00e7\u00e3o ou classifica\u00e7\u00e3o cont\u00e1bil.<\/p>\n\n\n\n<p>No entanto, dever\u00e1 ser estornado o cr\u00e9dito relativo a bens, adquiridos para revenda ou utilizados como insumos que tenham sido furtados ou roubados, inutilizados ou deteriorados, destru\u00eddos em sinistro, ou ainda, empregados em outros produtos que tenham tido a mesma destina\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Simples Nacional<\/strong><\/p>\n\n\n\n<p>Assim como no Lucro Presumido, a sua tributa\u00e7\u00e3o ser\u00e1 sobre a receita bruta. Neste caso, a perda de mercadoria n\u00e3o ir\u00e1 influenciar na apura\u00e7\u00e3o, tendo em vista que a receita bruta compreende o produto da venda de bens e servi\u00e7os nas opera\u00e7\u00f5es de conta pr\u00f3pria, o pre\u00e7o dos servi\u00e7os prestados e o resultado nas opera\u00e7\u00f5es em conta alheia, exclu\u00eddas as vendas canceladas e os descontos incondicionais concedidos. (Resolu\u00e7\u00e3o CSGN n\u00b0 140\/2018, artigo 2\u00b0, inciso II)<\/p>\n\n\n\n<p>Tamb\u00e9m comp\u00f5em a receita bruta o custo do financiamento nas vendas a prazo, contido no valor dos bens ou servi\u00e7os ou destacado no documento fiscal, as gorjetas, sejam elas compuls\u00f3rias ou n\u00e3o, os royalties, alugu\u00e9is e demais receitas decorrentes de cess\u00e3o de direito de uso ou gozo e as verbas de patroc\u00ednio (Resolu\u00e7\u00e3o CSGN n\u00b0 140\/2018, artigo 2\u00b0, \u00a7 4\u00b0).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Aspectos Cont\u00e1beis<\/strong><\/h2>\n\n\n\n<p>Os estoques ser\u00e3o mensurados pelo menor valor do custo ou do valor realiz\u00e1vel l\u00edquido, segundo a Resolu\u00e7\u00e3o CFC n\u00b0 1.170\/2009, item 9. Para forma\u00e7\u00e3o do valor de custo do estoque, ser\u00e3o inclusos os custos de aquisi\u00e7\u00e3o, transforma\u00e7\u00e3o, e todos os custos incorridos para trazer os estoques \u00e0 sua condi\u00e7\u00e3o e localiza\u00e7\u00e3o atuais.<\/p>\n\n\n\n<p>No item 34 desta resolu\u00e7\u00e3o, determina-se que todas as perdas de estoques devem ser reconhecidas como despesa do per\u00edodo, dedut\u00edvel ou n\u00e3o, em que a redu\u00e7\u00e3o ou a perda ocorrerem, ou seja seguindo o princ\u00edpio cont\u00e1bil da compet\u00eancia.<\/p>\n\n\n\n<p>Esses ajustes t\u00eam importantes reflexos fiscais, por isso, \u00e9 necess\u00e1ria a documenta\u00e7\u00e3o comprobat\u00f3ria para realizar os devidos ajustes, como prev\u00ea a Resolu\u00e7\u00e3o CFC n\u00b0 1.330\/2011, item 5, al\u00ednea \u201ce\u201d).<\/p>\n\n\n\n<p>\u00c9 de extrema import\u00e2ncia que as empresas fa\u00e7am frequentemente o levantamento do invent\u00e1rio f\u00edsico das mercadorias que est\u00e3o em seu estoque. Ao realiz\u00e1-lo, efetuam-se os poss\u00edveis ajustes das diferen\u00e7as apuradas entre o estoque f\u00edsico e o estoque registrado no invent\u00e1rio.&nbsp;<\/p>\n\n\n\n<p>Ocorrendo o furto, roubo ou desfalque, seja por funcion\u00e1rios ou terceiros, com a confirma\u00e7\u00e3o desta situa\u00e7\u00e3o, dever\u00e1 proceder a baixa desses bens ou mercadorias do seu estoque, lan\u00e7ando a contrapartida do ajuste em uma conta de despesa operacional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Exemplos Cont\u00e1beis<\/strong><\/h2>\n\n\n\n<p>Para auxiliar na compreens\u00e3o vejamos alguns exemplos cont\u00e1beis:<\/p>\n\n\n\n<p><strong>Exemplo 1: Furtos e roubos<\/strong><\/p>\n\n\n\n<p>O lan\u00e7amento relativo \u00e0 regulariza\u00e7\u00e3o dos estoques, desde que possua a documenta\u00e7\u00e3o comprobat\u00f3ria, na hip\u00f3tese de ajuste em rela\u00e7\u00e3o a furto e roubos das perdas apuradas no invent\u00e1rio:<\/p>\n\n\n\n<p>Perdas de Estoques (Conta de Resultado)<\/p>\n\n\n\n<p>Estoques (Ativo Circulante)<\/p>\n\n\n\n<p>Caso trate-se de furto realizado por funcion\u00e1rio e haja ressarcimento do valor do objeto furtado:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Sal\u00e1rios a Pagar (Passivo Circulante)<\/li><li>Estoques (Ativo Circulante)<\/li><\/ul>\n\n\n\n<p><strong>Exemplo 2: Avarias<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Perdas de Estoques (Conta de Resultado)<\/li><li>Estoques (Ativo Circulante)<\/li><\/ul>\n\n\n\n<p><strong>Exemplo 3: Falhas gerenciais e operacionais<\/strong><\/p>\n\n\n\n<p>Considerando empresa com controle permanente de estoque tenha apurado diverg\u00eancia em rela\u00e7\u00e3o ao estoque f\u00edsico e cont\u00e1bil em rela\u00e7\u00e3o a equ\u00edvoco da movimenta\u00e7\u00e3o dos estoques.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Saldo gerencial a menor:<\/li><\/ul>\n\n\n\n<p>&#8211; Estoques de Mercadorias (Ativo Circulante)<\/p>\n\n\n\n<p>&#8211; Custo das Mercadorias Vendidas (Conta de Resultado)<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Saldo gerencial a maior:<\/li><\/ul>\n\n\n\n<p>&#8211; Custo das Mercadorias Vendidas (Conta de Resultado)<\/p>\n\n\n\n<p>&#8211; Estoques (Ativo Circulante)<\/p>\n\n\n\n<p>Observa\u00e7\u00e3o:<\/p>\n\n\n\n<p>Em ambos os exemplos em se tratando de empresa que apropriou o cr\u00e9dito dos impostos, dever\u00e1 realizar o estorno destes:<\/p>\n\n\n\n<p>&#8211; Perdas de Estoques (Conta de Resultado)<\/p>\n\n\n\n<p>&#8211; ICMS a Recuperar (Ativo Circulante)<\/p>\n\n\n\n<p>&#8211; PIS a Recuperar (Ativo Circulante)<\/p>\n\n\n\n<p>&#8211; COFINS a Recuperar (Ativo Circulante)<\/p>\n\n\n\n<p>Salve este link e tenha sempre com voc\u00ea um guia completo de an\u00e1lise tribut\u00e1ria e cont\u00e1bil de perda de mercadoria.<\/p>\n\n\n\n<p>Para evoluir a sua contabilidade, conte sempre com a nossa equipe. Fale conosco: (41) 3028-8000 | <a href=\"mailto:alessandro@buildingprofits.com.br\">alessandro@buildingprofits.com.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste guia, a Building Profits re\u00fane todas as orienta\u00e7\u00f5es para o tratamento tribut\u00e1rio e cont\u00e1bil adequado \u00e0 perda de mercadorias do estoque. Voc\u00ea sabe, exatamente, como proceder no seu neg\u00f3cio diante das dificuldades de controle interno e gest\u00e3o de mercadorias? Leia at\u00e9 o fim! A perda de mercadorias n\u00e3o poderia ser algo comum, no entanto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios"],"_links":{"self":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts\/694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/comments?post=694"}],"version-history":[{"count":1,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts\/694\/revisions"}],"predecessor-version":[{"id":705,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/posts\/694\/revisions\/705"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/media\/625"}],"wp:attachment":[{"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/media?parent=694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/categories?post=694"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/priory.com.br\/bprh\/wp-json\/wp\/v2\/tags?post=694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}